{"id":49,"date":"2010-06-26T14:23:07","date_gmt":"2010-06-26T14:23:07","guid":{"rendered":"http:\/\/www.digitnut.com\/wordpress\/"},"modified":"2012-06-07T08:28:48","modified_gmt":"2012-06-07T08:28:48","slug":"sviluppo-di-app-in-outsourcing","status":"publish","type":"page","link":"https:\/\/www.digitnut.com\/wordpress\/cosa-facciamo\/sviluppo-di-app-in-outsourcing\/","title":{"rendered":"Sviluppo di App in Outsourcing"},"content":{"rendered":"<p><figure class=\"image_frame image_frame_right\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.digitnut.com\/wordpress\/wp-content\/uploads\/2010\/06\/ousourcing.png\" width=\"313\" height=\"110\" alt=\"\" \/><\/figure>\nGestiamo e coordiniamo progetti di sviluppo in outsourcing anche con time-to-market estremamente ristretti, avvalendoci di partnership esclusivamente con personale altamente specializzato e mission-critical.<\/p>\n<h1>Crowdsourcing<\/h1>\n<p><figure class=\"image_frame image_frame_left\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.digitnut.com\/wordpress\/wp-content\/uploads\/2010\/06\/crowdsourcing.png\" width=\"174\" height=\"311\" alt=\"\" \/><\/figure>\nUna nuova forma di produzione utilizzata da Digitnut riguarda inoltre progetti di sviluppo in crowdsourcing attraverso piattaforme User Generated Content verticali e specialistiche.<\/p>\n<p><strong>Richiedi subito un preventivo senza impegni!<\/strong><\/p>\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f295-o1\" lang=\"\" dir=\"ltr\" data-wpcf7-id=\"295\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/wordpress\/wp-json\/wp\/v2\/pages\/49#wpcf7-f295-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"295\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f295-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p>Nome e Cognome \/ Ragione Sociale (richiesto)\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n<\/p>\n<p>Email (richiesto)\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n<\/p>\n<p>Telefono (richiesto)\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-phone\" \/><\/span>\n<\/p>\n<p>Oggetto\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span>\n<\/p>\n<p>Messaggio\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"31\" rows=\"6\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span>\n<\/p>\n<p>Inserisci il seguente codice: <input type=\"hidden\" name=\"_wpcf7_captcha_challenge_captcha-170\" value=\"3137930013\" \/><img loading=\"lazy\" decoding=\"async\" class=\"wpcf7-form-control wpcf7-captchac wpcf7-captcha-captcha-170\" width=\"72\" height=\"24\" alt=\"captcha\" src=\"https:\/\/www.digitnut.com\/wordpress\/wp-content\/uploads\/wpcf7_captcha\/3137930013.png\" \/><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"captcha-170\"><input size=\"4\" maxlength=\"4\" class=\"wpcf7-form-control wpcf7-captchar\" autocomplete=\"off\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"captcha-170\" \/><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Invia\" \/>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"152\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Gestiamo e coordiniamo progetti di sviluppo in outsourcing anche con time-to-market estremamente ristretti, avvalendoci di partnership esclusivamente con personale altamente specializzato e mission-critical. Crowdsourcing Una nuova forma di produzione utilizzata da Digitnut riguarda inoltre progetti di sviluppo in crowdsourcing attraverso piattaforme User Generated Content verticali e specialistiche. Richiedi subito un preventivo senza impegni!<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":19,"menu_order":6,"comment_status":"closed","ping_status":"open","template":"","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-49","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"progetti di sviluppo in outsourcing con partnership esclusivamente con personale altamente specializzato e mission-critical.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.digitnut.com\/wordpress\/cosa-facciamo\/sviluppo-di-app-in-outsourcing\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Digitnut | mobile 4U | web and mobile application\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"App dev Outsourcing | Digitnut\" \/>\n\t\t<meta property=\"og:description\" content=\"progetti di sviluppo in outsourcing con partnership esclusivamente con personale altamente specializzato e mission-critical.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.digitnut.com\/wordpress\/cosa-facciamo\/sviluppo-di-app-in-outsourcing\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2010-06-26T14:23:07+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2012-06-07T08:28:48+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"App dev Outsourcing | Digitnut\" \/>\n\t\t<meta name=\"twitter:description\" content=\"progetti di sviluppo in outsourcing con partnership esclusivamente con personale altamente specializzato e mission-critical.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.digitnut.com\\\/wordpress\\\/cosa-facciamo\\\/sviluppo-di-app-in-outsourcing\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.digitnut.com\\\/wordpress#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.digitnut.com\\\/wordpress\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.digitnut.com\\\/wordpress\\\/cosa-facciamo\\\/#listItem\",\"name\":\"Digital\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.digitnut.com\\\/wordpress\\\/cosa-facciamo\\\/#listItem\",\"position\":2,\"name\":\"Digital\",\"item\":\"https:\\\/\\\/www.digitnut.com\\\/wordpress\\\/cosa-facciamo\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.digitnut.com\\\/wordpress\\\/cosa-facciamo\\\/sviluppo-di-app-in-outsourcing\\\/#listItem\",\"name\":\"Sviluppo di App in Outsourcing\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.digitnut.com\\\/wordpress#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.digitnut.com\\\/wordpress\\\/cosa-facciamo\\\/sviluppo-di-app-in-outsourcing\\\/#listItem\",\"position\":3,\"name\":\"Sviluppo di App in Outsourcing\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.digitnut.com\\\/wordpress\\\/cosa-facciamo\\\/#listItem\",\"name\":\"Digital\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.digitnut.com\\\/wordpress\\\/#organization\",\"name\":\"Digitnut\",\"description\":\"mobile 4U | web and mobile application\",\"url\":\"https:\\\/\\\/www.digitnut.com\\\/wordpress\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.digitnut.com\\\/wordpress\\\/cosa-facciamo\\\/sviluppo-di-app-in-outsourcing\\\/#webpage\",\"url\":\"https:\\\/\\\/www.digitnut.com\\\/wordpress\\\/cosa-facciamo\\\/sviluppo-di-app-in-outsourcing\\\/\",\"name\":\"App dev Outsourcing | Digitnut\",\"description\":\"progetti di sviluppo in outsourcing con partnership esclusivamente con personale altamente specializzato e mission-critical.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.digitnut.com\\\/wordpress\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.digitnut.com\\\/wordpress\\\/cosa-facciamo\\\/sviluppo-di-app-in-outsourcing\\\/#breadcrumblist\"},\"datePublished\":\"2010-06-26T14:23:07+00:00\",\"dateModified\":\"2012-06-07T08:28:48+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.digitnut.com\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.digitnut.com\\\/wordpress\\\/\",\"name\":\"Digitnut\",\"description\":\"mobile 4U | web and mobile application\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.digitnut.com\\\/wordpress\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"App dev Outsourcing | Digitnut","description":"progetti di sviluppo in outsourcing con partnership esclusivamente con personale altamente specializzato e mission-critical.","canonical_url":"https:\/\/www.digitnut.com\/wordpress\/cosa-facciamo\/sviluppo-di-app-in-outsourcing\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.digitnut.com\/wordpress\/cosa-facciamo\/sviluppo-di-app-in-outsourcing\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.digitnut.com\/wordpress#listItem","position":1,"name":"Home","item":"https:\/\/www.digitnut.com\/wordpress","nextItem":{"@type":"ListItem","@id":"https:\/\/www.digitnut.com\/wordpress\/cosa-facciamo\/#listItem","name":"Digital"}},{"@type":"ListItem","@id":"https:\/\/www.digitnut.com\/wordpress\/cosa-facciamo\/#listItem","position":2,"name":"Digital","item":"https:\/\/www.digitnut.com\/wordpress\/cosa-facciamo\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.digitnut.com\/wordpress\/cosa-facciamo\/sviluppo-di-app-in-outsourcing\/#listItem","name":"Sviluppo di App in Outsourcing"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.digitnut.com\/wordpress#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.digitnut.com\/wordpress\/cosa-facciamo\/sviluppo-di-app-in-outsourcing\/#listItem","position":3,"name":"Sviluppo di App in Outsourcing","previousItem":{"@type":"ListItem","@id":"https:\/\/www.digitnut.com\/wordpress\/cosa-facciamo\/#listItem","name":"Digital"}}]},{"@type":"Organization","@id":"https:\/\/www.digitnut.com\/wordpress\/#organization","name":"Digitnut","description":"mobile 4U | web and mobile application","url":"https:\/\/www.digitnut.com\/wordpress\/"},{"@type":"WebPage","@id":"https:\/\/www.digitnut.com\/wordpress\/cosa-facciamo\/sviluppo-di-app-in-outsourcing\/#webpage","url":"https:\/\/www.digitnut.com\/wordpress\/cosa-facciamo\/sviluppo-di-app-in-outsourcing\/","name":"App dev Outsourcing | Digitnut","description":"progetti di sviluppo in outsourcing con partnership esclusivamente con personale altamente specializzato e mission-critical.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.digitnut.com\/wordpress\/#website"},"breadcrumb":{"@id":"https:\/\/www.digitnut.com\/wordpress\/cosa-facciamo\/sviluppo-di-app-in-outsourcing\/#breadcrumblist"},"datePublished":"2010-06-26T14:23:07+00:00","dateModified":"2012-06-07T08:28:48+00:00"},{"@type":"WebSite","@id":"https:\/\/www.digitnut.com\/wordpress\/#website","url":"https:\/\/www.digitnut.com\/wordpress\/","name":"Digitnut","description":"mobile 4U | web and mobile application","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.digitnut.com\/wordpress\/#organization"}}]},"og:locale":"en_US","og:site_name":"Digitnut | mobile 4U | web and mobile application","og:type":"article","og:title":"App dev Outsourcing | Digitnut","og:description":"progetti di sviluppo in outsourcing con partnership esclusivamente con personale altamente specializzato e mission-critical.","og:url":"https:\/\/www.digitnut.com\/wordpress\/cosa-facciamo\/sviluppo-di-app-in-outsourcing\/","article:published_time":"2010-06-26T14:23:07+00:00","article:modified_time":"2012-06-07T08:28:48+00:00","twitter:card":"summary","twitter:title":"App dev Outsourcing | Digitnut","twitter:description":"progetti di sviluppo in outsourcing con partnership esclusivamente con personale altamente specializzato e mission-critical."},"aioseo_meta_data":{"post_id":"49","title":"App dev Outsourcing | #site_title","description":"progetti di sviluppo in outsourcing con partnership esclusivamente con personale altamente specializzato e mission-critical.","keywords":[{"label":"sviluppo app","value":"sviluppo app"},{"label":"outsourcing","value":"outsourcing"},{"label":"crowdsourcing","value":"crowdsourcing"}],"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-02-04 04:50:11","updated":"2025-12-10 08:47:27","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.digitnut.com\/wordpress\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.digitnut.com\/wordpress\/cosa-facciamo\/\" title=\"Digital\">Digital<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSviluppo di App in Outsourcing\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.digitnut.com\/wordpress"},{"label":"Digital","link":"https:\/\/www.digitnut.com\/wordpress\/cosa-facciamo\/"},{"label":"Sviluppo di App in Outsourcing","link":"https:\/\/www.digitnut.com\/wordpress\/cosa-facciamo\/sviluppo-di-app-in-outsourcing\/"}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/PYm68-N","_links":{"self":[{"href":"https:\/\/www.digitnut.com\/wordpress\/wp-json\/wp\/v2\/pages\/49","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.digitnut.com\/wordpress\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.digitnut.com\/wordpress\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.digitnut.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.digitnut.com\/wordpress\/wp-json\/wp\/v2\/comments?post=49"}],"version-history":[{"count":0,"href":"https:\/\/www.digitnut.com\/wordpress\/wp-json\/wp\/v2\/pages\/49\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.digitnut.com\/wordpress\/wp-json\/wp\/v2\/pages\/19"}],"wp:attachment":[{"href":"https:\/\/www.digitnut.com\/wordpress\/wp-json\/wp\/v2\/media?parent=49"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}